{"id":5637,"date":"2022-06-10T10:35:00","date_gmt":"2022-06-10T08:35:00","guid":{"rendered":"https:\/\/www.d-flight.it\/new_portal\/?p=5637"},"modified":"2022-06-15T10:45:28","modified_gmt":"2022-06-15T08:45:28","slug":"__trashed-2","status":"publish","type":"post","link":"https:\/\/www.d-flight.it\/new_portal\/en\/__trashed-2\/","title":{"rendered":"The D-Flight Support Desk for the BVLOS flight from Grottaglie to Manduria. The Italian demonstration of the CORUS-XUAM Project presented"},"content":{"rendered":"<p>Sessione Dimostrativa Italiana 7-8-9 Giugno 2022<\/p>\n\n\n\n<p>I servizi aerei urbani (Urban Air Mobility) realizzati con i droni in  aree ad alta densit\u00e0 abitativa rappresentano una realt\u00e0 in veloce  evoluzione. La dimostrazione italiana del progetto CORUS-XUAM, svoltasi  nei giorni 7-8-9 giugno 2022 nell\u2019area di Grottaglie-Manduria, ha  confermato che l\u2019attuale stato di maturit\u00e0 tecnologica ed operativa dei  sistemi per il coordinamento e l\u2019interoperabilit\u00e0 del sistema nazionale  di gestione dello spazio aereo e dello U-Space (lo spazio aereo dedicato  ai droni) \u00e8 gi\u00e0 adeguato ad operare servizi di trasporto emergenziale  con droni in aree periurbane e urbane.<br> <\/p>\n\n\n\n<p>Il progetto internazionale  CORUS-XUAM, co-finanziato dalla SESAR Joint Undertaking tramite il  programma Europeo Horizon 2020, coordinato da EUROCONTROL, ha come  obiettivo quello di testare operazioni integrate di aeromobili <em>manned<\/em> e <em>unmanned <\/em>di  differenti categorie attraverso l\u2019utilizzo di servizi avanzati U-Space  in ambienti urbani, extra-urbani e in spazi aerei in prossimit\u00e0 di  aeroporti. Sono inoltre oggetto di studio le modalit\u00e0 per facilitare  un\u2019apposita interfaccia tra il mondo U-Space e quello dell\u2019Air Traffic  Management. Nell\u2019ambito del progetto sono identificate differenti  campagne dimostrative con ben sette paesi europei coinvolti: Italia,  Belgio, Francia, Germania, Spagna, Svezia e Regno Unito.  <br>  <\/p>\n\n\n\n<p>L\u2019obiettivo primario della dimostrazione italiana \u00e8 quello di effettuare  operazioni aeree di Urban Air Mobility, eseguite con Unmanned Aircraft  System (UAS) e velivoli pilotati all\u2019interno dello U-Space. Quest\u2019ultimo  rappresenta un insieme di funzioni e processi digitali automatizzati in  uno spazio aereo definito, finalizzati a garantire ai droni e agli  altri operatori la piena integrazione nello spazio aereo in modo sicuro  ed efficiente. Lo U-Space fornisce un quadro di riferimento per  facilitare lo svolgimento di operazioni di volo di ogni tipo anche nel  contesto urbano e sub-urbano.<br> La tipologia di operazione di Urban  Air Mobility oggetto della dimostrazione \u00e8 afferente al trasporto  d\u2019urgenza contestualizzato in uno scenario operativo e logistico  variegato che coinvolge un aeroporto civile, un\u2019aviosuperficie  posizionata in luogo sub-urbano e un\u2019area urbana.<br> Lo scenario  rappresentato include un UAS cargo per il trasporto di un carico di  natura medico\/sanitaria da un hub centrale (nello scenario reale  l\u2019aeroporto e Test Bed di Grottaglie), fino ad un \u2018drone porto\u2019  (l\u2019aviosuperficie sub-urbana, AEROTRE Aviosuperfice Manduria). In  contemporanea, ed entro i limiti di sicurezza, sono state condotte altre  operazioni UAS. I servizi U-Space, erogati dalla piattaforma di  D-Flight, la societ\u00e0 del Gruppo ENAV in partnership con Leonardo e  Telespazio,e utilizzati da tutti i piloti di droni coinvolti, hanno  permesso una gestione sicura delle varie operazioni, sia relativamente  agli obblighi di autorizzazione al volo sia al tracciamento e  monitoraggio degli gli UAS in volo. <br> <\/p>\n\n\n\n<p>All\u2019arrivo dell\u2019UAS cargo  sull\u2019aviosuperficie di Manduria, una parte del carico \u00e8 stato  predisposto per l\u2019operazione di consegna finale su un drone di massa al  decollo di circa 25 Kg, che lo ha trasportato, con una operazione  cosiddetta in BVLOS (Beyond Visual Line Of Sight) cio\u00e8 quando il  velivolo opera fuori dal campo visivo del pilota dal \u2018drone porto\u2019  sub-urbano all\u2019interno dell\u2019area urbana di Manduria, nei pressi  dell\u2019ospedale (trasporto di ultimo miglio). <br> <\/p>\n\n\n\n<p>Durante le  dimostrazioni \u00e8 stato utilizzato il Drone Detection System di D-Flight,  un sistema dotato di antenne e apparati, in grado di rilevare la  presenza di droni \u201cnon collaborativi\u201d, identificando numero di serie,  nome del proprietario, posizione del pilota con relative coordinate di  decollo, rotta di volo, posizione, direzione, altitudine e velocit\u00e0.<br>  <\/p>\n\n\n\n<p>Un altro elemento rilevante per la demo italiana di CORUS XUAM \u00e8  l\u2019attivit\u00e0 di coordinamento tra l\u2019ATM e lo U-Space per la gestione di  operazioni particolari come quelle di emergenza (es. volo ambulanza),  che decolla da uno spazio aereo controllato (aeroporto) e necessita di  operare all\u2019interno dello U-Space. Tale operazione \u00e8 stata condotta  attraverso il coordinamento tra ENAV, la societ\u00e0 che gestisce il  traffico aereo civile in Italia e l\u2019Operational <em>Support Desk<\/em> di  D-Flight. Quest\u2019ultimo, operando di fatto sul sistema di D-Flight,  riesce ad inviare le informazioni di interesse agli utenti U-Space, in  maniera automatizzata. <br>Oltre ad ENAV e D-Flight, hanno partecipano  alla dimostrazione anche i partner Pipistrel  Vertical Solutions  (Slovenia) operatore del UAS cargo, Techno Sky, societ\u00e0 del Gruppo ENAV  Italia con l\u2019operatore UAS e il responsabile dell\u2019operazione BVLOS di  \u201clast mile delivery\u201d, il Distretto Tecnologico Aerospaziale \u2013 DTA  (Italia) che ha coordinato l\u2019attivit\u00e0 logistica autorizzativa e  sperimentale presso il test bed aeroportuale di Grottaglie, e NAIS \u2013  Nextant Applications and Innovative Solutions (Italia), che ha il  compito di riportare i risultati delle validazioni degli aspetti di  safety, accessibilit\u00e0 ed equit\u00e0 dello spazio aereo, cyber security, e  human performance.<br> <\/p>\n\n\n\n<p>Per ENAV, la preparazione e conduzione della  sperimentazione CORUS-XUAM ha permesso di affrontare l\u2019accomodation  dell\u2019UAM valutando le sinergie necessarie tra il mondo ATM e quello  U-Space per poter consentire l\u2019impiego in modo sicuro dei mezzi a  pilotaggio remoto anche in aree controllate dello spazio aereo.<br> <\/p>\n\n\n\n<p>Per  D-Flight, la preparazione e conduzione della sperimentazione CORUS-XUAM  ha permesso di maturare ulteriormente i servizi U-Space e raccogliere  preziosi feedback per l\u2019industrializzazione e certificazione come USSP \u2013  U-Space Service Provider. La comprovata esperienza in ambito ATM e  U-Space acquisita da ENAV e D-Flight, permetter\u00e0 al Gruppo ENAV di  contribuire significativamente alla definizione del concetto operativo  UAM europeo, dimostrandone l\u2019applicabilit\u00e0 nel contesto italiano e  assicurandone la corrispondenza con gli interessi nazionali e le  strategie aziendali.<br> <\/p>\n\n\n\n<p>Per il DTA, il progetto CORUS-XUAM evidenzia  che il Grottaglie Airport Test Bed \u00e8 uno strumento per lo sviluppo di  conoscenze innovative per l\u2019automazione dei servizi di gestione del  traffico aereo e dei servizi di Urban Air Mobility verso un sistema di  trasporti sostenibile, \u00e8 un volano per uno sviluppo tecnologico  integrato e coordinato per le aziende nazionali ed europee, \u00e8 un fattore  di attrazione di investimenti e di sviluppo industriale in Puglia.<br> <\/p>\n\n\n\n<p> La mobilit\u00e0 aerea urbana rappresenta dunque uno dei sistemi pi\u00f9  sostenibiliper il futuro dei trasporti e, come per la mobilit\u00e0 aerea  tradizionale, le attivit\u00e0 di ricerca, sviluppo e innovazione sono  necessarie per maturare concetti e tecnologie abilitanti per la  realizzazione del sistema di gestione dello spazio aereo urbano e  sub-urbano. <\/p>","protected":false},"excerpt":{"rendered":"<p>Sessione Dimostrativa Italiana 7-8-9 Giugno 2022 I servizi aerei urbani (Urban Air Mobility) realizzati con i droni in aree ad alta densit\u00e0 abitativa rappresentano una realt\u00e0 in veloce evoluzione. La dimostrazione italiana del progetto CORUS-XUAM, svoltasi nei giorni 7-8-9 giugno&hellip;<\/p>","protected":false},"author":1,"featured_media":5638,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[69],"tags":[66,70,68,67],"class_list":["post-5637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-d-flight","tag-droni","tag-enac","tag-enav","post_emotion_main_smile","post_emotion_smile"],"_links":{"self":[{"href":"https:\/\/www.d-flight.it\/new_portal\/en\/wp-json\/wp\/v2\/posts\/5637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.d-flight.it\/new_portal\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.d-flight.it\/new_portal\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/en\/wp-json\/wp\/v2\/comments?post=5637"}],"version-history":[{"count":1,"href":"https:\/\/www.d-flight.it\/new_portal\/en\/wp-json\/wp\/v2\/posts\/5637\/revisions"}],"predecessor-version":[{"id":5639,"href":"https:\/\/www.d-flight.it\/new_portal\/en\/wp-json\/wp\/v2\/posts\/5637\/revisions\/5639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/en\/wp-json\/wp\/v2\/media\/5638"}],"wp:attachment":[{"href":"https:\/\/www.d-flight.it\/new_portal\/en\/wp-json\/wp\/v2\/media?parent=5637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/en\/wp-json\/wp\/v2\/categories?post=5637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/en\/wp-json\/wp\/v2\/tags?post=5637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}