{"id":4063,"date":"2020-05-28T11:15:22","date_gmt":"2020-05-28T09:15:22","guid":{"rendered":"https:\/\/www.d-flight.it\/new_portal\/?p=4063"},"modified":"2020-06-24T11:15:49","modified_gmt":"2020-06-24T09:15:49","slug":"nuova-modalita-di-esami-per-lattestato-di-pilota-apr","status":"publish","type":"post","link":"https:\/\/www.d-flight.it\/new_portal\/nuova-modalita-di-esami-per-lattestato-di-pilota-apr\/","title":{"rendered":"Nuova modalit\u00e0 di esami per l\u2019Attestato di Pilota APR"},"content":{"rendered":"\n<p>Se non hai ancora sostenuto l\u2019esame online sul <a href=\"https:\/\/www.enac.gov.it\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"sito ENAC (apre in una nuova scheda)\">sito ENAC<\/a> per ottenere il tuo <strong>Attestato di Pilota APR<\/strong> (Operazioni non critiche), ricordati che a partire dal 1 luglio 2020 sar\u00e0 necessario il pagamento dei diritti <em>prima<\/em> del sostenimento dell\u2019esame stesso. <\/p>\n\n\n\n<p>Se hai gi\u00e0 sostenuto l\u2019esame con successo ma devi ancora\npagare i diritti ad ENAC, ricordati di farlo <strong>entro e non oltre le ore 16.00\ndel giorno 30 giugno 2020<\/strong>.<\/p>\n\n\n\n<p><em>Le prove d\u2019esame saranno comunque momentaneamente sospese\ndalle ore 16 del 25\/06\/2020 fino al 30\/06\/2020 per via dell\u2019attivazione della\nnuova modalit\u00e0.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se non hai ancora sostenuto l\u2019esame online sul sito ENAC per ottenere il tuo Attestato di Pilota APR (Operazioni non critiche), ricordati che a partire dal 1 luglio 2020 sar\u00e0 necessario il pagamento dei diritti prima del sostenimento dell\u2019esame stesso.&hellip;<\/p>\n","protected":false},"author":1,"featured_media":4064,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[69],"tags":[70,68],"class_list":["post-4063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-droni","tag-enac","post_emotion_main_wtf","post_emotion_wtf","post_emotion_angry","post_emotion_sad","post_emotion_smile","post_emotion_lol"],"_links":{"self":[{"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/posts\/4063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/comments?post=4063"}],"version-history":[{"count":0,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/posts\/4063\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/media\/4064"}],"wp:attachment":[{"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/media?parent=4063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/categories?post=4063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/tags?post=4063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}