{"id":4833,"date":"2021-06-24T12:08:25","date_gmt":"2021-06-24T10:08:25","guid":{"rendered":"https:\/\/www.d-flight.it\/new_portal\/?p=4833"},"modified":"2021-06-24T15:40:59","modified_gmt":"2021-06-24T13:40:59","slug":"nasce-il-manifesto-per-lo-spazio-aereo-dei-droni-d-flight-in-campo-per-il-decollo-del-settore","status":"publish","type":"post","link":"https:\/\/www.d-flight.it\/new_portal\/nasce-il-manifesto-per-lo-spazio-aereo-dei-droni-d-flight-in-campo-per-il-decollo-del-settore\/","title":{"rendered":"NASCE IL MANIFESTO PER LO SPAZIO AEREO DEI DRONI"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">D-Flight in campo per il decollo del settore<\/h3>\n\n\n\n<p>Roma, 24 giugno 2021 &#8211; Nasce il <em>Manifesto<\/em> per lo\nsviluppo dei servizi U-Space, lo spazio dedicato ai velivoli unmanned impiegati\nanche in operazioni complesse. D-Flight lancia i primi servizi U-Space di\nNetworking Electronic Remote Identification e di Traffic Information (NRI),\nvolti a favorire la crescita del settore attraverso iniziative di\nsperimentazione ed una sempre maggior <em>geo-awareness<\/em> nei cieli italiani, promuovendo\nl\u2019adesione su base volontaria al servizio di identificazione remota dei mezzi\nUAS (Unmanned Aircraft Systems).<\/p>\n\n\n\n<p><strong>Il protocollo D-Flight per il servizio di Networking Remote e-Identification, basato sull\u2019Interface Control Document <\/strong>pubblicato sul sito, consentir\u00e0 lo sviluppo di sistemi in grado di comunicare, su rete IP, l\u2019identit\u00e0 e la posizione di un mezzo, direttamente da bordo o da terra, per il tramite di una Ground Control Station.  Il documento di scambio ICD \u00e8 disponibile, insieme alla licenza d&#8217;uso, nella sezione Networking Remote e-Identification (NRI) di: <a rel=\"noreferrer noopener\" href=\"https:\/\/www.d-flight.it\/new_portal\/servizi-d-flight\/#altri-servizi\" target=\"_blank\">altri servizi<\/a>. <\/p>\n\n\n\n<p>Implementando\nil protocollo, gli operatori dei mezzi UAS che intenderanno utilizzare i\nservizi promossi, sempre nel pieno rispetto del GDPR sulla Privacy, contribuiranno\nalla realizzazione di un quadro complessivo della situazione di traffico a\nbassa quota rappresentato da D-Flight sotto forma di <strong>Traffic Information Service (TIS)<\/strong>. In linea con il concetto di electronic conspicuity,\nintrodotta dal pacchetto regolamentare U-Space recentemente adottato dal\nparlamento europeo ,contribuiranno al completamento della consapevolezza\ngeografica&nbsp; i servizi gi\u00e0 attivi e\nraccomandati dall\u2019ENAC di Drone Operation Area (DOA) per le operazioni in\ncategoria <em>Open<\/em>, &nbsp;Drone Operation\nPlan (DOP), gi\u00e0 obbligatoria per le operazioni oltre il campo visivo nelle\ncategoria <em>Specific<\/em> o <em>Certified<\/em>, nonch\u00e9 le tracce dei mezzi manned\nvisibili dalle reti di sorveglianza cooperativa ADS-B. per tutti i piloti VDS\nche vorranno inviare la propria posizione &nbsp;tramite l\u2019App D-Flight.<\/p>\n\n\n\n<p><em>L\u2019iniziativa lanciata con il Manifesto U-Space, con il favore dell\u2019ENAC che ne promuove gli obiettivi <\/em>\u2013 dichiara <strong>l\u2019AD <\/strong>di<strong> D-Flight Cristiano Baldoni<\/strong> \u2013 <em>\u00e8 un passo fondamentale per garantire un\u2019evoluzione del settore sempre in sicurezza e nel rispetto dei protocolli sviluppati da ENAC e D-Flight. L\u2019Interface Control Document (ICD) rappresenta il mezzo attraverso il quale posizionamento e identificazione degli UAS renderanno lo U-Space conforme alla normativa europea, permettendo un tracking accurato per uno spazio aereo fruibile nella piena consapevolezza della sua occupazione in tempo reale. Auspichiamo che la collaborazione con ENAC \u2013 <\/em>prosegue Baldoni<em> \u2013 renda D-Flight sempre pi\u00f9 elemento centrale per il raggiungimento dei target stabiliti dalla roadmap europea nella realizzazione di uno U-Space all\u2019avanguardia e innovativo per lo sviluppo del settore ed in prospettiva, per la realizzazione del Piano di Advanced Air Mobility.<\/em><\/p>\n\n\n\n<p><a href=\"https:\/\/www.d-flight.it\/new_portal\/wp-content\/uploads\/2021\/06\/Italian-U-Space-Manifest-ITA_FIN_Rev.-2-002.pdf\">Scarica il Manifesto<\/a><br><a href=\"\/new_portal\/servizi-d-flight\/#altri-servizi\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (apre in una nuova scheda)\">Scarica l&#8217;ICD (sezione Networking Remote e-Identification &#8211; NRI di: altri servizi)<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>D-Flight in campo per il decollo del settore Roma, 24 giugno 2021 &#8211; Nasce il Manifesto per lo sviluppo dei servizi U-Space, lo spazio dedicato ai velivoli unmanned impiegati anche in operazioni complesse. D-Flight lancia i primi servizi U-Space di&hellip;<\/p>\n","protected":false},"author":1,"featured_media":4838,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[69],"tags":[68,105,106],"class_list":["post-4833","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-enac","tag-manifesto-u-space","tag-servizi-u-space","post_emotion_main_smile","post_emotion_smile","post_emotion_wow","post_emotion_angry","post_emotion_wtf","post_emotion_lol"],"_links":{"self":[{"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/posts\/4833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/comments?post=4833"}],"version-history":[{"count":0,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/posts\/4833\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/media\/4838"}],"wp:attachment":[{"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/media?parent=4833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/categories?post=4833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/tags?post=4833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}