{"id":4922,"date":"2021-11-18T11:47:30","date_gmt":"2021-11-18T10:47:30","guid":{"rendered":"https:\/\/www.d-flight.it\/new_portal\/?p=4922"},"modified":"2021-11-18T11:47:39","modified_gmt":"2021-11-18T10:47:39","slug":"d-flight-alla-settima-edizione-del-roma-drone-conference","status":"publish","type":"post","link":"https:\/\/www.d-flight.it\/new_portal\/d-flight-alla-settima-edizione-del-roma-drone-conference\/","title":{"rendered":"D-Flight alla settima edizione del Roma Drone Conference"},"content":{"rendered":"\n<p>Roma, 18 novembre 2021 &#8211; D-Flight partecipa con un proprio&nbsp;<em>Info Point&nbsp;<\/em>alla settima edizione del&nbsp;<strong>Roma Drone Conference<\/strong>, evento dedicato al mondo degli&nbsp;<em>Unammned Vehicles<\/em>.<\/p>\n\n\n\n<p>Al centro della convention i temi di maggior attualit\u00e0 del settore, la situazione del mercato dei velivoli a pilotaggio remoto e la contestuale evoluzione normativa del settore.<\/p>\n\n\n\n<p>Ampio risalto al futuro impiego dei droni nell\u2019ambito della Urban Air Mobility, per una mobilit\u00e0 efficiente, sicura e sostenibile anche nelle nostre citt\u00e0.<\/p>\n\n\n\n<p>Questo il tema trattato anche da&nbsp;<strong>Maurizio Paggetti,&nbsp;<\/strong><em>Chief Operating Offier<\/em>&nbsp;di ENAV e AD di D-Flight, nel corso del proprio intervento nel quale sono stati delineati l\u2019impegno della Societ\u00e0 nella ricerca, sviluppo e innovazione tecnologica, tutti elementi necessari per garantire un sempre maggior efficace ecosistema del mondo droni.<\/p>\n\n\n\n<p>Previsti inoltre nella giornata gli interventi di<strong>&nbsp;Cristiano Baldoni,&nbsp;<\/strong><em>Business System Operation<\/em>&nbsp;D-Flight,sulla realizzazione dello U-Space in Italia e di&nbsp;<strong>Alberto Iovino<\/strong><em>, Operational Support ENAV&nbsp;<\/em>sul tema dell\u2019integrazione tra ATM e U-Space.<\/p>\n\n\n\n<p>D-Flight, con l\u2019allestimento del proprio&nbsp;<em>info point<\/em>&nbsp;mette a disposizione di visitatori e utenti la possibilit\u00e0 di conoscere e approfondire le funzionalit\u00e0 della piattaforma con dimostrazioni&nbsp;<em>real time&nbsp;<\/em>della stessa e dei tool previsti tra i servizi a valore aggiunto per il volo dei droni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 18 novembre 2021 &#8211; D-Flight partecipa con un proprio&nbsp;Info Point&nbsp;alla settima edizione del&nbsp;Roma Drone Conference, evento dedicato al mondo degli&nbsp;Unammned Vehicles. Al centro della convention i temi di maggior attualit\u00e0 del settore, la situazione del mercato dei velivoli a&hellip;<\/p>\n","protected":false},"author":1,"featured_media":4923,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[69],"tags":[68,108],"class_list":["post-4922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-enac","tag-roma-dorne-conference","post_emotion_main_smile","post_emotion_smile"],"_links":{"self":[{"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/posts\/4922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/comments?post=4922"}],"version-history":[{"count":0,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/posts\/4922\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/media\/4923"}],"wp:attachment":[{"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/media?parent=4922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/categories?post=4922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/tags?post=4922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}