{"id":5154,"date":"2022-04-20T10:31:45","date_gmt":"2022-04-20T08:31:45","guid":{"rendered":"https:\/\/www.d-flight.it\/new_portal\/?p=5154"},"modified":"2022-04-20T10:59:44","modified_gmt":"2022-04-20T08:59:44","slug":"anche-i-droni-per-la-logistica-lintervento-dellad-maurizio-paggetti","status":"publish","type":"post","link":"https:\/\/www.d-flight.it\/new_portal\/anche-i-droni-per-la-logistica-lintervento-dellad-maurizio-paggetti\/","title":{"rendered":"Anche i droni per la logistica. L\u2019intervento dell\u2019AD Maurizio Paggetti"},"content":{"rendered":"\n<p>Sono sempre pi\u00f9\nambiziose e diversificate le nuove prospettive del trasporto aereo che spingono\nENAV a guardare non pi\u00f9 alla sola gestione del traffico aereo, bens\u00ec alla\ngestione dello spazio aereo, intesa come infrastruttura disponibile per una\ncrescita del settore e per realizzare gli obiettivi di un volo sempre pi\u00f9\nefficiente e sostenibile. <\/p>\n\n\n\n<p>In questo\nscenario, il mondo dei droni sta evolvendo con fervente continuit\u00e0, sia in\ntermini di regolamentazione sia per investimenti industriali, con societ\u00e0\nimpegnate da tempo nella nuova frontiera della cosiddetta Advance Air Mobility,\ncostituita dagli obiettivi di trasporto e mobilit\u00e0 con mezzi a pilotaggio\nremoto. Un mercato che conter\u00e0 nel 2026 un valore in dollari di oltre 40\nmiliardi. <\/p>\n\n\n\n<p>Il lavoro di ENAV\nin quest&#8217;ottica, attraverso D-Flight, societ\u00e0 del Gruppo partecipata da\nLeonardo e Telespazio, \u00e8 quello di garantire che il settore possa vedere\nrealizzato lo U-Space in Italia, lo spazio aereo dedicato ai droni, e che possa\naffrontare attraverso la propria piattaforma le sfide che il settore <em>unmanned<\/em>\npropone in termini di sicurezza, efficienza e armonizzazione con il trasporto\naereo tradizionale. In Italia a oggi sono circa 110 mila gli utenti iscritti\nalla piattaforma D-Flight per l&#8217;utilizzo dei servizi per droni. <\/p>\n\n\n\n<p>Questa nuova\nrealt\u00e0 abbraccia infatti due layer fondamentali come i servizi legati al mondo\nAtm convenzionale e quelli sviluppati per il mondo dei droni, per i quali sono\nin continua implementazione nuovi processi di innovazione digitale per\nl&#8217;utilizzo di tecnologie sempre pi\u00f9 all&#8217;avanguardia in grado di armonizzare\nl&#8217;uso dello &#8220;spazio aereo&#8221; aprendolo a nuovi soggetti. In\nquest&#8217;ottica si inizia a sviluppare il concetto operativo dell&#8217;Urban Air\nTraffic Management (UATM). <\/p>\n\n\n\n<p>L&#8217;evoluzione ci\nporta ora a dover considerare questo nuovo aspetto, sia per i droni dedicati al\ntrasporto merci o per esempio al monitoraggio infrastrutture, sia per il\ntrasporto delle persone su distanze anche di 35-40 chilometri. La specificit\u00e0\ndelle operazioni, gli investimenti sulla tecnologia e l&#8217;automazione del volo, ci\nspingono verso nuovi orizzonti. Unendo queste capacit\u00e0 a un sistema di regole\ncerte, saremo in grado di orientare anche gli investimenti sia di natura\ntecnologica sia di evoluzione del business, elemento al quale gli stakeholder\nguardano con grande attenzione. <\/p>\n\n\n\n<p>Secondo questo\norientamento, in collaborazione con Enac e le societ\u00e0 di gestione degli\naeroporti di Roma (AdR), Milano (Sea) e Venezia (Save), Enav ha sottoscritto un\nMemorandum of understanding per la creazione di un &#8220;Ecosistema italiano\nper la \u201cMobilit\u00e0 Aerea Avanzata&#8221;, intesa come sviluppo di nuovi concetti\noperativi, necessit\u00e0 di regolazione e nuove tecnologie per l&#8217;abilitazione di un\nsettore che guidi l&#8217;Italia verso la terza dimensione della mobilit\u00e0, quella\nverticale, e che permetta al Paese di giocare un ruolo da protagonista\nnell&#8217;adozione e fornitura di prodotti di mobilit\u00e0 aerea integrata. Queste\niniziative indicano un orizzonte relativamente vicino, considerato l&#8217;obiettivo\ndi fornire servizi di aerotaxi e mobilit\u00e0 avanzata gi\u00e0 in occasione dei giochi\ninvernali di Milano-Cortina 2026 o nell&#8217;ambito del Pums (Piano urbano della\nmobilit\u00e0 sostenibile) del Comune di Roma, per i quali il sistema dell&#8217;intero\nsettore sta implementando tecnologie e investendo su continue collaborazioni. <\/p>\n\n\n\n<p>Taxi volanti e\ntrasporto logistico in ambito urbano sono solo alcuni dei progetti che mirano a\nrealizzare il concetto di smart city, elemento al quale ENAV guarda con grande\ninteresse per una completa maturazione tecnologica dei servizi e per garantire\nuno sbocco nuovo di decongestionamento delle citt\u00e0 con iniziative sempre pi\u00f9\nefficienti. Questi elementi sono stati racchiusi nella sperimentazione\n&#8220;Sumeri&#8221;, in collaborazione con Enac, Leonardo e il Comune di Torino,\ndove droni di 130 chili in grado di trasportare carichi fino a 25 chili hanno\nvolato sui cieli della citt\u00e0 piemontese nel rispetto dei pi\u00f9 elevati standard\ndi sicurezza e sviluppando soluzioni ad alto contenuto tecnologico. <\/p>\n\n\n\n<p>Avanzate\nsperimentazioni per il monitoraggio ambientale e infrastrutturale, cos\u00ec come\nper il trasporto di materiale biomedico, trovano risalto a testimonianza di\nquanto il settore guardi a un&#8217;ampia gamma di attivit\u00e0 in grado di garantire,\nanche in condizioni critiche, assistenza e continuit\u00e0 di servizi essenziali. <\/p>\n\n\n\n<p>Tra gli altri\nprogetti, ENAV \u00e8 stata impegnata infatti anche per la validazione dei sistemi e\nl&#8217;utilizzo della propria piattaforma D-Flight dedicata ai servizi per droni,\ncon Enac, Telespazio e l&#8217;ospedale pediatrico Bambino Ges\u00f9, nella\nsperimentazione di trasporto e consegna di materiale biomedico con un drone\nelettrico tra il centro di prelievo di Santa Marinella e quello di analisi di\nPalidoro con la percorrenza di una rotta di oltre 3o chilometri, il tutto in\nmodalit\u00e0 di controllo automatico oltre il campo visivo dell&#8217;operatore (Beyond\nVisual Line of Sight &#8211; BVLOS). <\/p>\n\n\n\n<p>La capacit\u00e0, quindi, di avere una vision del settore che cambia, e la mission di adeguare alle nuove esigenze di traffico le infrastrutture e le collaborazioni tra enti, \u00e8 alla base del successo di questa affascinante sfida.<\/p>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/www.d-flight.it\/new_portal\/wp-content\/uploads\/2022\/04\/Airpress_Paggetti-1.pdf\">Scarica l&#8217;articolo<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sono sempre pi\u00f9 ambiziose e diversificate le nuove prospettive del trasporto aereo che spingono ENAV a guardare non pi\u00f9 alla sola gestione del traffico aereo, bens\u00ec alla gestione dello spazio aereo, intesa come infrastruttura disponibile per una crescita del settore&hellip;<\/p>\n","protected":false},"author":1,"featured_media":5162,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[69,1],"tags":[67],"class_list":["post-5154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-other","tag-enav"],"_links":{"self":[{"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/posts\/5154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/comments?post=5154"}],"version-history":[{"count":7,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/posts\/5154\/revisions"}],"predecessor-version":[{"id":5167,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/posts\/5154\/revisions\/5167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/media\/5162"}],"wp:attachment":[{"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/media?parent=5154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/categories?post=5154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.d-flight.it\/new_portal\/wp-json\/wp\/v2\/tags?post=5154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}